{"id":3169,"date":"2024-06-27T10:25:49","date_gmt":"2024-06-27T10:25:49","guid":{"rendered":"https:\/\/fabricadeprofile.com\/?post_type=product&#038;p=3169"},"modified":"2024-10-31T18:09:20","modified_gmt":"2024-10-31T18:09:20","slug":"ancadrament-fereastra-s126","status":"publish","type":"product","link":"https:\/\/fabricadeprofile.com\/it\/prodotto\/telaio-della-finestra-s126\/","title":{"rendered":"Telaio della finestra AF126"},"content":{"rendered":"<p>Il design esterno del vostro edificio \u00e8 importante quanto quello interno!<\/p>\n<p>I nostri profili esterni daranno un carattere unico alla vostra propriet\u00e0.<\/p>\n<p>Offriamo una grande selezione e i migliori prezzi in Romania! Oltre 1000 misure e varianti diverse.<\/p>\n<p>I nostri profili sono adatti sia per l'esterno che per l'interno degli edifici.<\/p>\n<p>Specifiche tecniche:<\/p>\n<ul>\n<li>Tecnologia di produzione unica con base in polistirolo EPS-200 rivestita di quarzo e resina.<\/li>\n<li>La nostra tecnologia di produzione consente di ottenere una superficie altamente resistente.<\/li>\n<li>Perfetta protezione dagli agenti atmosferici Protezione dai raggi UV e rispettosa dell'ambiente.<\/li>\n<li>Resistenza alle muffe.<\/li>\n<li>Installazione facile e veloce.<\/li>\n<li>Non sono necessarie viti o chiodi.<\/li>\n<li>Durevole e resistente agli urti.<\/li>\n<li>Aggiungete una grande estetica al vostro edificio.<\/li>\n<li>Il 90% \u00e8 pi\u00f9 leggero della sua controparte in calcestruzzo.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p><span class=\"iconite\" style=\"font-size: 24px; padding: 5px;\"><br \/>\n<span id=\"su_tooltip_6a04a82b13dcd_button\" class=\"su-tooltip-button su-tooltip-button-outline-yes\" aria-describedby=\"su_tooltip_6a04a82b13dcd\" data-settings='{\"position\":\"top\",\"behavior\":\"hover\",\"hideDelay\":0}' tabindex=\"0\"><span>\ud83c\udf26\ufe0f<\/span><\/span><span style=\"display:none;z-index:100\" id=\"su_tooltip_6a04a82b13dcd\" class=\"su-tooltip\" role=\"tooltip\"><span class=\"su-tooltip-inner su-tooltip-shadow-no\" style=\"z-index:100;background:#222222;color:#FFFFFF;font-size:16px;border-radius:5px;text-align:left;max-width:300px;line-height:1.25\"><span class=\"su-tooltip-title\"><\/span><span class=\"su-tooltip-content su-u-trim\">Resistente agli urti e agli agenti atmosferici<\/span><\/span><span id=\"su_tooltip_6a04a82b13dcd_arrow\" class=\"su-tooltip-arrow\" style=\"z-index:100;background:#222222\" data-popper-arrow><\/span><\/span><br \/>\n<span id=\"su_tooltip_6a04a82b13e4e_button\" class=\"su-tooltip-button su-tooltip-button-outline-yes\" aria-describedby=\"su_tooltip_6a04a82b13e4e\" data-settings='{\"position\":\"top\",\"behavior\":\"hover\",\"hideDelay\":0}' tabindex=\"0\"><span>\ud83d\udee0\ufe0f<\/span><\/span><span style=\"display:none;z-index:100\" id=\"su_tooltip_6a04a82b13e4e\" class=\"su-tooltip\" role=\"tooltip\"><span class=\"su-tooltip-inner su-tooltip-shadow-no\" style=\"z-index:100;background:#222222;color:#FFFFFF;font-size:16px;border-radius:5px;text-align:left;max-width:300px;line-height:1.25\"><span class=\"su-tooltip-title\"><\/span><span class=\"su-tooltip-content su-u-trim\">Durata 20 anni<\/span><\/span><span id=\"su_tooltip_6a04a82b13e4e_arrow\" class=\"su-tooltip-arrow\" style=\"z-index:100;background:#222222\" data-popper-arrow><\/span><\/span><br \/>\n<span id=\"su_tooltip_6a04a82b13ea4_button\" class=\"su-tooltip-button su-tooltip-button-outline-yes\" aria-describedby=\"su_tooltip_6a04a82b13ea4\" data-settings='{\"position\":\"top\",\"behavior\":\"hover\",\"hideDelay\":0}' tabindex=\"0\"><span>\u267b\ufe0f<\/span><\/span><span style=\"display:none;z-index:100\" id=\"su_tooltip_6a04a82b13ea4\" class=\"su-tooltip\" role=\"tooltip\"><span class=\"su-tooltip-inner su-tooltip-shadow-no\" style=\"z-index:100;background:#222222;color:#FFFFFF;font-size:16px;border-radius:5px;text-align:left;max-width:300px;line-height:1.25\"><span class=\"su-tooltip-title\"><\/span><span class=\"su-tooltip-content su-u-trim\">Riciclabile<\/span><\/span><span id=\"su_tooltip_6a04a82b13ea4_arrow\" class=\"su-tooltip-arrow\" style=\"z-index:100;background:#222222\" data-popper-arrow><\/span><\/span><br \/>\n<span id=\"su_tooltip_6a04a82b13ef2_button\" class=\"su-tooltip-button su-tooltip-button-outline-yes\" aria-describedby=\"su_tooltip_6a04a82b13ef2\" data-settings='{\"position\":\"top\",\"behavior\":\"hover\",\"hideDelay\":0}' tabindex=\"0\"><span>\ud83c\udfe0 &amp; \ud83c\udfe2<\/span><\/span><span style=\"display:none;z-index:100\" id=\"su_tooltip_6a04a82b13ef2\" class=\"su-tooltip\" role=\"tooltip\"><span class=\"su-tooltip-inner su-tooltip-shadow-no\" style=\"z-index:100;background:#222222;color:#FFFFFF;font-size:16px;border-radius:5px;text-align:left;max-width:300px;line-height:1.25\"><span class=\"su-tooltip-title\"><\/span><span class=\"su-tooltip-content su-u-trim\">Per interni\/esterni<\/span><\/span><span id=\"su_tooltip_6a04a82b13ef2_arrow\" class=\"su-tooltip-arrow\" style=\"z-index:100;background:#222222\" data-popper-arrow><\/span><\/span><br \/>\n<span id=\"su_tooltip_6a04a82b13f3b_button\" class=\"su-tooltip-button su-tooltip-button-outline-yes\" aria-describedby=\"su_tooltip_6a04a82b13f3b\" data-settings='{\"position\":\"top\",\"behavior\":\"hover\",\"hideDelay\":0}' tabindex=\"0\"><span>\ud83c\udf3f<\/span><\/span><span style=\"display:none;z-index:100\" id=\"su_tooltip_6a04a82b13f3b\" class=\"su-tooltip\" role=\"tooltip\"><span class=\"su-tooltip-inner su-tooltip-shadow-no\" style=\"z-index:100;background:#222222;color:#FFFFFF;font-size:16px;border-radius:5px;text-align:left;max-width:300px;line-height:1.25\"><span class=\"su-tooltip-title\"><\/span><span class=\"su-tooltip-content su-u-trim\">Materiale naturale<\/span><\/span><span id=\"su_tooltip_6a04a82b13f3b_arrow\" class=\"su-tooltip-arrow\" style=\"z-index:100;background:#222222\" data-popper-arrow><\/span><\/span><br \/>\n<span id=\"su_tooltip_6a04a82b13f82_button\" class=\"su-tooltip-button su-tooltip-button-outline-yes\" aria-describedby=\"su_tooltip_6a04a82b13f82\" data-settings='{\"position\":\"top\",\"behavior\":\"hover\",\"hideDelay\":0}' tabindex=\"0\"><span>\ud83c\udfa8<\/span><\/span><span style=\"display:none;z-index:100\" id=\"su_tooltip_6a04a82b13f82\" class=\"su-tooltip\" role=\"tooltip\"><span class=\"su-tooltip-inner su-tooltip-shadow-no\" style=\"z-index:100;background:#222222;color:#FFFFFF;font-size:16px;border-radius:5px;text-align:left;max-width:300px;line-height:1.25\"><span class=\"su-tooltip-title\"><\/span><span class=\"su-tooltip-content su-u-trim\">Verniciabile<\/span><\/span><span id=\"su_tooltip_6a04a82b13f82_arrow\" class=\"su-tooltip-arrow\" style=\"z-index:100;background:#222222\" data-popper-arrow><\/span><\/span><br \/>\n<\/span><\/p>","protected":false},"featured_media":3293,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[]},"product_brand":[],"product_cat":[56],"product_tag":[],"class_list":{"0":"post-3169","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-ancadramente-ferestre","7":"desktop-align-left","8":"tablet-align-left","9":"mobile-align-left","11":"first","12":"instock","13":"sale","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.9 (Yoast SEO v25.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ancadrament fereastr\u0103 AF126 | fabricadeprofile.com<\/title>\n<meta name=\"description\" content=\"Ancadramentele de ferestre reprezint\u0103 elemente decorative ce confer\u0103 un aspect elegant \u0219i finisat fa\u021badei casei tale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fabricadeprofile.com\/it\/prodotto\/telaio-della-finestra-s126\/?wmc-currency=EUR\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ancadrament fereastr\u0103 AF126\" \/>\n<meta property=\"og:description\" content=\"Ancadramentele de ferestre reprezint\u0103 elemente decorative ce confer\u0103 un aspect elegant \u0219i finisat fa\u021badei casei tale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fabricadeprofile.com\/it\/prodotto\/telaio-della-finestra-s126\/?wmc-currency=EUR\" \/>\n<meta property=\"og:site_name\" content=\"fabricadeprofile.com\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-31T18:09:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fabricadeprofile.com\/wp-content\/uploads\/2024\/06\/S-126.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"488\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prezzo\" \/>\n\t<meta name=\"twitter:data1\" content=\"30,00&nbsp;lei\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e0\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fabricadeprofile.com\/it\/prodotto\/telaio-della-finestra-s126\/\",\"url\":\"https:\/\/fabricadeprofile.com\/it\/prodotto\/telaio-della-finestra-s126\/\",\"name\":\"Ancadrament fereastr\u0103 AF126 | fabricadeprofile.com\",\"isPartOf\":{\"@id\":\"https:\/\/fabricadeprofile.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/fabricadeprofile.com\/it\/prodotto\/telaio-della-finestra-s126\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/fabricadeprofile.com\/it\/prodotto\/telaio-della-finestra-s126\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/fabricadeprofile.com\/wp-content\/uploads\/2024\/06\/S-126.jpg\",\"datePublished\":\"2024-06-27T10:25:49+00:00\",\"dateModified\":\"2024-10-31T18:09:20+00:00\",\"description\":\"Ancadramentele de ferestre reprezint\u0103 elemente decorative ce confer\u0103 un aspect elegant \u0219i finisat fa\u021badei casei tale.\",\"breadcrumb\":{\"@id\":\"https:\/\/fabricadeprofile.com\/it\/prodotto\/telaio-della-finestra-s126\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fabricadeprofile.com\/it\/prodotto\/telaio-della-finestra-s126\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/fabricadeprofile.com\/it\/prodotto\/telaio-della-finestra-s126\/#primaryimage\",\"url\":\"https:\/\/fabricadeprofile.com\/wp-content\/uploads\/2024\/06\/S-126.jpg\",\"contentUrl\":\"https:\/\/fabricadeprofile.com\/wp-content\/uploads\/2024\/06\/S-126.jpg\",\"width\":680,\"height\":488},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fabricadeprofile.com\/it\/prodotto\/telaio-della-finestra-s126\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\/\/fabricadeprofile.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/fabricadeprofile.com\/it\/magazin\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ancadrament fereastr\u0103 AF126\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fabricadeprofile.com\/#website\",\"url\":\"https:\/\/fabricadeprofile.com\/\",\"name\":\"fabricadeprofile.com\",\"description\":\"Fa din cas\u0103, acas\u0103\",\"publisher\":{\"@id\":\"https:\/\/fabricadeprofile.com\/#organization\"},\"alternateName\":\"Fabricadeprofile\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fabricadeprofile.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/fabricadeprofile.com\/#organization\",\"name\":\"fabricadeprofile.com\",\"url\":\"https:\/\/fabricadeprofile.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/fabricadeprofile.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/fabricadeprofile.com\/wp-content\/uploads\/2023\/02\/fabricadeprofile.com_.png\",\"contentUrl\":\"https:\/\/fabricadeprofile.com\/wp-content\/uploads\/2023\/02\/fabricadeprofile.com_.png\",\"width\":500,\"height\":500,\"caption\":\"fabricadeprofile.com\"},\"image\":{\"@id\":\"https:\/\/fabricadeprofile.com\/#\/schema\/logo\/image\/\"},\"publishingPrinciples\":\"https:\/\/fabricadeprofile.com\/it\/termini-e-condizioni\/\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"30.00\" \/>\n<meta property=\"product:price:currency\" content=\"RON\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Telaio per finestra AF126 | fabricadeprofile.com","description":"Le cornici delle finestre sono elementi decorativi che conferiscono un aspetto elegante e rifinito alla facciata della vostra casa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fabricadeprofile.com\/it\/prodotto\/telaio-della-finestra-s126\/?wmc-currency=EUR","og_locale":"it_IT","og_type":"article","og_title":"Ancadrament fereastr\u0103 AF126","og_description":"Ancadramentele de ferestre reprezint\u0103 elemente decorative ce confer\u0103 un aspect elegant \u0219i finisat fa\u021badei casei tale.","og_url":"https:\/\/fabricadeprofile.com\/it\/prodotto\/telaio-della-finestra-s126\/?wmc-currency=EUR","og_site_name":"fabricadeprofile.com","article_modified_time":"2024-10-31T18:09:20+00:00","og_image":[{"width":680,"height":488,"url":"https:\/\/fabricadeprofile.com\/wp-content\/uploads\/2024\/06\/S-126.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Prezzo":"30,00&nbsp;lei","Disponibilit\u00e0":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fabricadeprofile.com\/it\/prodotto\/telaio-della-finestra-s126\/","url":"https:\/\/fabricadeprofile.com\/it\/prodotto\/telaio-della-finestra-s126\/","name":"Telaio per finestra AF126 | fabricadeprofile.com","isPartOf":{"@id":"https:\/\/fabricadeprofile.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fabricadeprofile.com\/it\/prodotto\/telaio-della-finestra-s126\/#primaryimage"},"image":{"@id":"https:\/\/fabricadeprofile.com\/it\/prodotto\/telaio-della-finestra-s126\/#primaryimage"},"thumbnailUrl":"https:\/\/fabricadeprofile.com\/wp-content\/uploads\/2024\/06\/S-126.jpg","datePublished":"2024-06-27T10:25:49+00:00","dateModified":"2024-10-31T18:09:20+00:00","description":"Le cornici delle finestre sono elementi decorativi che conferiscono un aspetto elegante e rifinito alla facciata della vostra casa.","breadcrumb":{"@id":"https:\/\/fabricadeprofile.com\/it\/prodotto\/telaio-della-finestra-s126\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fabricadeprofile.com\/it\/prodotto\/telaio-della-finestra-s126\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/fabricadeprofile.com\/it\/prodotto\/telaio-della-finestra-s126\/#primaryimage","url":"https:\/\/fabricadeprofile.com\/wp-content\/uploads\/2024\/06\/S-126.jpg","contentUrl":"https:\/\/fabricadeprofile.com\/wp-content\/uploads\/2024\/06\/S-126.jpg","width":680,"height":488},{"@type":"BreadcrumbList","@id":"https:\/\/fabricadeprofile.com\/it\/prodotto\/telaio-della-finestra-s126\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/fabricadeprofile.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/fabricadeprofile.com\/it\/magazin\/"},{"@type":"ListItem","position":3,"name":"Ancadrament fereastr\u0103 AF126"}]},{"@type":"WebSite","@id":"https:\/\/fabricadeprofile.com\/#website","url":"https:\/\/fabricadeprofile.com\/","name":"fabricadeprofile.com","description":"Sentirsi a casa","publisher":{"@id":"https:\/\/fabricadeprofile.com\/#organization"},"alternateName":"Fabricadeprofile","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fabricadeprofile.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/fabricadeprofile.com\/#organization","name":"fabricadeprofile.com","url":"https:\/\/fabricadeprofile.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/fabricadeprofile.com\/#\/schema\/logo\/image\/","url":"https:\/\/fabricadeprofile.com\/wp-content\/uploads\/2023\/02\/fabricadeprofile.com_.png","contentUrl":"https:\/\/fabricadeprofile.com\/wp-content\/uploads\/2023\/02\/fabricadeprofile.com_.png","width":500,"height":500,"caption":"fabricadeprofile.com"},"image":{"@id":"https:\/\/fabricadeprofile.com\/#\/schema\/logo\/image\/"},"publishingPrinciples":"https:\/\/fabricadeprofile.com\/it\/termini-e-condizioni\/"}]},"product_price_amount":"30.00","product_price_currency":"RON","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/fabricadeprofile.com\/it\/wp-json\/wp\/v2\/product\/3169"}],"collection":[{"href":"https:\/\/fabricadeprofile.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/fabricadeprofile.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/fabricadeprofile.com\/it\/wp-json\/wp\/v2\/comments?post=3169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fabricadeprofile.com\/it\/wp-json\/wp\/v2\/media\/3293"}],"wp:attachment":[{"href":"https:\/\/fabricadeprofile.com\/it\/wp-json\/wp\/v2\/media?parent=3169"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/fabricadeprofile.com\/it\/wp-json\/wp\/v2\/product_brand?post=3169"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/fabricadeprofile.com\/it\/wp-json\/wp\/v2\/product_cat?post=3169"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/fabricadeprofile.com\/it\/wp-json\/wp\/v2\/product_tag?post=3169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}